{"id":5824,"date":"2016-10-14T16:27:46","date_gmt":"2016-10-14T14:27:46","guid":{"rendered":"http:\/\/mein-pegasus.de\/?p=5824"},"modified":"2026-01-05T17:45:35","modified_gmt":"2026-01-05T16:45:35","slug":"5824-2","status":"publish","type":"post","link":"https:\/\/hppsycho.de\/mediathek\/2016\/10\/14\/5824-2\/","title":{"rendered":"25.Lektion &#8211; Diagnosekriterien der Schizophrenie nach der ICD-10"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Sie m\u00fcssen sich anmelden, um diesen Inhalt einsehen zu k\u00f6nnen. Bitte <a class=\"swpm-login-link\" href=\"https:\/\/hppsycho.de\/mediathek\/membership-login\/\">Anmelden<\/a>. Kein Mitglied? <a href=\"https:\/\/hppsycho.de\/mediathek\/membership-join\/\">Werden Sie Mitglied bei uns<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Sie m\u00fcssen sich anmelden, um diesen Inhalt einsehen zu k\u00f6nnen. Bitte Anmelden. Kein Mitglied? Werden Sie Mitglied bei uns<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[164,336,168,9],"tags":[],"class_list":["post-5824","post","type-post","status-publish","format-standard","hentry","category-learnletter","category-lektion","category-psychosen_learnletter","category-psychotherapie"],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":5829,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/10\/14\/26-lektion-andere-psychotische-stoerungen\/","url_meta":{"origin":5824,"position":0},"title":"26. Lektion &#8211; andere psychotische St\u00f6rungen","author":"","date":false,"format":false,"excerpt":"Die Schizophrenie ist wohl die bekannteste psychotische St\u00f6rung. Sie vereint die meisten psychotischen Merkmale, kann aber auch sehr unterschiedlich auftreten. Daneben gibt es noch andere psychotische St\u00f6rungen. Anhaltende Wahnhafte St\u00f6rung Sie ist gekennzeichnet durch die Entwicklung einer einzelnen Wahnidee oder mehrerer aufeinander bezogenen Wahninhalte (systematisierter Wahn) zu den Themen Vor\u00fcbergehende\u2026","rel":"","context":"In &quot;learnletter&quot;","block_context":{"text":"learnletter","link":"https:\/\/hppsycho.de\/mediathek\/category\/learnletter\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2677,"url":"https:\/\/hppsycho.de\/mediathek\/2015\/12\/08\/diagnose-der-schizophrenie\/","url_meta":{"origin":5824,"position":1},"title":"Diagnose der Schizophrenie","author":"","date":false,"format":false,"excerpt":"Diagnostik und Differentialdiagnostik Die Diagnose st\u00fctzt sich bei einer Schizophrenie in erster Linie auf: 1.\u00a0\u00a0\u00a0 den psychopathologischen Befund 2.\u00a0\u00a0\u00a0 den Ausschluss anderer psychischer St\u00f6rungen 3.\u00a0\u00a0\u00a0 den Ausschluss einer k\u00f6rperlichen Erkrankung Sind die Kriterien nach ICD-10 (F20) nicht erf\u00fcllt, sind \u00e4hnlich aussehende psychotische oder wahnhafte St\u00f6rungen zu beachten (F21-F24). Sind die\u2026","rel":"","context":"In &quot;hpp&quot;","block_context":{"text":"hpp","link":"https:\/\/hppsycho.de\/mediathek\/category\/hpp\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5822,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/10\/14\/lektion-24-psychosen-und-schizophrenie\/","url_meta":{"origin":5824,"position":2},"title":"24. Lektion &#8211; Psychosen und Schizophrenie","author":"","date":false,"format":false,"excerpt":"Die Schizophrenie besch\u00e4ftigt die Wissenschaft sehr und vor allem von Anfang an. Das liegt vor allem an ihrer unterschiedlichen Erscheinung. Symptome nach Bleuler Bleuler unterscheidet in charakteristischen Grundsymptomen und akzessorischen Symptomen, die auch bei anderen Psychosen auftreten k\u00f6nnen. Grundsymptome nach Bleuler Assoziationslockerung (formale Denkst\u00f6rung, Denkzerfahrenheit) Affektst\u00f6rungen (z.B. Parathymie) Autismus (St\u00f6rung\u2026","rel":"","context":"In &quot;learnletter&quot;","block_context":{"text":"learnletter","link":"https:\/\/hppsycho.de\/mediathek\/category\/learnletter\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2671,"url":"https:\/\/hppsycho.de\/mediathek\/2015\/12\/08\/symptome-im-einzelnen\/","url_meta":{"origin":5824,"position":3},"title":"Symptome im Einzelnen","author":"","date":false,"format":false,"excerpt":"Inhaltliche Denkst\u00f6rungen (Wahn) Hier treten vor allem Wahnwahrnehmung und Personenverkennung auf (Symptome 1. Ranges, Schneider). Wahneinf\u00e4lle \u00e4u\u00dfern sich vornehmlich als Verfolgungs-, Vergiftungs- oder Beeintr\u00e4chtigungswahn und als Gr\u00f6\u00dfen- und Abstammungswahn. Weniger typisch ist hypochondrischer Wahn. Wahnideen haben eher einen magisch-mystischen Charakter (Wetterkontrollieren, Au\u00dferirdische). Allem voraus geht oft die Wahnstimmung (alles ist\u2026","rel":"","context":"In &quot;hpp&quot;","block_context":{"text":"hpp","link":"https:\/\/hppsycho.de\/mediathek\/category\/hpp\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2669,"url":"https:\/\/hppsycho.de\/mediathek\/2015\/12\/08\/symptome-der-schizophrenie\/","url_meta":{"origin":5824,"position":4},"title":"Symptome der Schizophrenie","author":"","date":false,"format":false,"excerpt":"Symptome der Schizophrenie nach Bleuler Bleuler unterscheidet in charakteristischen Grundsymptomen und akzessorischen Symptomen, die auch bei anderen Psychosen auftreten k\u00f6nnen. Grundsymptome nach Bleuler Assoziationslockerung (formale Denkst\u00f6rung, Denkzerfahrenheit) Affektst\u00f6rungen (z.B. Parathymie) Autismus (St\u00f6rung des Antriebs) Ambivalenz Akzessorische Symptome\u00a0\u00a0\u00a0 Wahrnehmungsst\u00f6rungen (Halluzinationen) Inhaltliche Denkst\u00f6rungen (Wahn) Katatone St\u00f6rungen Symptome nach K. Schneider Kurt Schneider\u2026","rel":"","context":"In &quot;hpp&quot;","block_context":{"text":"hpp","link":"https:\/\/hppsycho.de\/mediathek\/category\/hpp\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5820,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/10\/14\/23-lektion-die-systematik-der-schizophrenie\/","url_meta":{"origin":5824,"position":5},"title":"23. Lektion  &#8211; Die Systematik der Schizophrenie","author":"","date":false,"format":false,"excerpt":"Die Schizophrenie geh\u00f6rt zu den psychotischen St\u00f6rungen.\u00a0Menschen mit psychotischen St\u00f6rungen haben vor allem den Verlust der Realit\u00e4t gemein. Sie glauben, verfolgt zu werden, nehmen Dinge wahr, die nicht existent sind, haben den Eindruck, Ihre Gedanken werden entzogen oder glauben, ferngesteuert zu werden - um einige Symptome zu nennen. Im Vordergrund\u2026","rel":"","context":"In &quot;learnletter&quot;","block_context":{"text":"learnletter","link":"https:\/\/hppsycho.de\/mediathek\/category\/learnletter\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts\/5824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/comments?post=5824"}],"version-history":[{"count":1,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts\/5824\/revisions"}],"predecessor-version":[{"id":18049,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts\/5824\/revisions\/18049"}],"wp:attachment":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/media?parent=5824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/categories?post=5824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/tags?post=5824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}