{"id":4075,"date":"2016-07-14T12:44:25","date_gmt":"2016-07-14T10:44:25","guid":{"rendered":"http:\/\/hppsycho.de\/?p=4075"},"modified":"2017-09-24T22:39:40","modified_gmt":"2017-09-24T20:39:40","slug":"das-abhaengigkeitssyndrom","status":"publish","type":"post","link":"https:\/\/hppsycho.de\/mediathek\/2016\/07\/14\/das-abhaengigkeitssyndrom\/","title":{"rendered":"Video &#8211; Das Abh\u00e4ngigkeitssyndrom"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Sie m\u00fcssen sich anmelden, um diesen Inhalt einsehen zu k\u00f6nnen. Bitte <a class=\"swpm-login-link\" href=\"https:\/\/hppsycho.de\/mediathek\/membership-login\/\">Anmelden<\/a>. Kein Mitglied? <a href=\"https:\/\/hppsycho.de\/mediathek\/membership-join\/\">Werden Sie Mitglied bei uns<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Sie m\u00fcssen sich anmelden, um diesen Inhalt einsehen zu k\u00f6nnen. Bitte Anmelden. Kein Mitglied? Werden Sie Mitglied bei uns<\/p>\n","protected":false},"author":1,"featured_media":4541,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[141,57,150],"tags":[],"class_list":["post-4075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abhaengigkeit","category-video","category-sucht_videos"],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":3829,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/07\/05\/abhaengigkeit-alkohol-cannabis-und-kokain\/","url_meta":{"origin":4075,"position":0},"title":"Video &#8211; Abh\u00e4ngigkeit &#8211; Alkohol, Cannabis und Kokain","author":"","date":false,"format":false,"excerpt":"","rel":"","context":"In &quot;Abh\u00e4ngigkeit&quot;","block_context":{"text":"Abh\u00e4ngigkeit","link":"https:\/\/hppsycho.de\/mediathek\/category\/abhaengigkeit\/"},"img":{"alt_text":"","src":"https:\/\/videos.files.wordpress.com\/hDFcN5bE\/hpp_sucht_01_alkohol_cannabis_kokain_hd.original.jpg?w=350&h=200&crop=1","width":350,"height":200},"classes":[]},{"id":4081,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/07\/14\/die-entstehung-von-abhaengigkeit\/","url_meta":{"origin":4075,"position":1},"title":"Video &#8211; Die Entstehung von Abh\u00e4ngigkeit","author":"","date":false,"format":false,"excerpt":"","rel":"","context":"In &quot;Abh\u00e4ngigkeit&quot;","block_context":{"text":"Abh\u00e4ngigkeit","link":"https:\/\/hppsycho.de\/mediathek\/category\/abhaengigkeit\/"},"img":{"alt_text":"","src":"https:\/\/videos.files.wordpress.com\/njk6FqvF\/hpp_sucht_03_sucht_entstehung_hd.original.jpg?w=350&h=200&crop=1","width":350,"height":200},"classes":[]},{"id":4078,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/07\/14\/die-therapiephasen-bei-der-behaqndlung-von-abhaengigkeiten\/","url_meta":{"origin":4075,"position":2},"title":"Video &#8211; Die Therapiephasen bei der Behandlung von Abh\u00e4ngigkeiten","author":"","date":false,"format":false,"excerpt":"","rel":"","context":"In &quot;Abh\u00e4ngigkeit&quot;","block_context":{"text":"Abh\u00e4ngigkeit","link":"https:\/\/hppsycho.de\/mediathek\/category\/abhaengigkeit\/"},"img":{"alt_text":"","src":"https:\/\/videos.files.wordpress.com\/4h4miZOs\/hpp_sucht_04_sucht_therapiephasen_hd.original.jpg?w=350&h=200&crop=1","width":350,"height":200},"classes":[]},{"id":4084,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/07\/14\/abhaengigkeit-von-opioiden-und-halluzinogen\/","url_meta":{"origin":4075,"position":3},"title":"Video &#8211; Abh\u00e4ngigkeit von Opioiden und Halluzinogen","author":"","date":false,"format":false,"excerpt":"","rel":"","context":"In &quot;Abh\u00e4ngigkeit&quot;","block_context":{"text":"Abh\u00e4ngigkeit","link":"https:\/\/hppsycho.de\/mediathek\/category\/abhaengigkeit\/"},"img":{"alt_text":"","src":"https:\/\/videos.files.wordpress.com\/m5MIBkVa\/hpp_sucht_02_opioide_halluzinogen_hd.original.jpg?w=350&h=200&crop=1","width":350,"height":200},"classes":[]},{"id":2872,"url":"https:\/\/hppsycho.de\/mediathek\/2015\/12\/18\/suchterkrankungen\/","url_meta":{"origin":4075,"position":4},"title":"Suchterkrankungen","author":"","date":false,"format":false,"excerpt":"Suchterkrankungen Fr\u00fcher wurde bei der Sucht die k\u00f6rperliche von der psychischen Abh\u00e4ngigkeit getrennt. Aufgrund der schweren Trennbarkeit verzichtet man heute auf diese Unterscheidung und f\u00fchrte den Begriff der Abh\u00e4ngigkeit ein. Im Folgenden besch\u00e4ftigen wir uns mit der stoffgebundenen Abh\u00e4ngigkeit. Beschreibung In der ICD-10 wird die Sucht in der Kategorie F10-F19,\u2026","rel":"","context":"In &quot;Abh\u00e4ngigkeit&quot;","block_context":{"text":"Abh\u00e4ngigkeit","link":"https:\/\/hppsycho.de\/mediathek\/category\/abhaengigkeit\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5895,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/10\/14\/48-lektion-stoerungen-durch-alkohol\/","url_meta":{"origin":4075,"position":5},"title":"48. Lektion &#8211; St\u00f6rungen durch Alkohol","author":"","date":false,"format":false,"excerpt":"Zun\u00e4chst einmal Prinzipielles zum Thema Abh\u00e4ngigkeit: Ein Abh\u00e4ngigkeitssyndrom ist durch starkes Verlangen, Kontrollverlust und k\u00f6rperliche Entzugssymptome, Toleranzentwicklung, Einengung auf den Substanzgebrauch und Fortsetzung des Konsums trotz k\u00f6rperlicher oder psychischer Sch\u00e4den gekennzeichnet. Eine Rolle bei Abh\u00e4ngigkeiten spielen genetische Faktoren, Lernfaktoren und nat\u00fcrlich soziale Faktoren wie Gruppenzugeh\u00f6rigkeit eine gro\u00dfe Rolle. Die Therapie\u2026","rel":"","context":"In &quot;learnletter&quot;","block_context":{"text":"learnletter","link":"https:\/\/hppsycho.de\/mediathek\/category\/learnletter\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts\/4075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/comments?post=4075"}],"version-history":[{"count":0,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts\/4075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/media?parent=4075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/categories?post=4075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/tags?post=4075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}