{"id":16897,"date":"2024-12-11T15:49:51","date_gmt":"2024-12-11T14:49:51","guid":{"rendered":"https:\/\/hppsycho.de\/mediathek\/?p=16897"},"modified":"2024-12-11T16:31:46","modified_gmt":"2024-12-11T15:31:46","slug":"verhaltenstherapeutische-techniken","status":"publish","type":"post","link":"https:\/\/hppsycho.de\/mediathek\/2024\/12\/11\/verhaltenstherapeutische-techniken\/","title":{"rendered":"Verhaltenstherapeutische Techniken"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Sie m\u00fcssen sich anmelden, um diesen Inhalt einsehen zu k\u00f6nnen. Bitte <a class=\"swpm-login-link\" href=\"https:\/\/hppsycho.de\/mediathek\/membership-login\/\">Anmelden<\/a>. Kein Mitglied? <a href=\"https:\/\/hppsycho.de\/mediathek\/membership-join\/\">Werden Sie Mitglied bei uns<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Sie m\u00fcssen sich anmelden, um diesen Inhalt einsehen zu k\u00f6nnen. Bitte Anmelden. Kein Mitglied? Werden Sie Mitglied bei uns<\/p>\n","protected":false},"author":1,"featured_media":905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[405],"tags":[],"class_list":["post-16897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verhaltenstherapie"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1","jetpack-related-posts":[{"id":2631,"url":"https:\/\/hppsycho.de\/mediathek\/2015\/12\/08\/verhaltenstherapie\/","url_meta":{"origin":16897,"position":0},"title":"Verhaltenstherapie","author":"","date":false,"format":false,"excerpt":"Verhaltenstherapie und kognitive Therapie Die Verhaltenstherapie hat sich aus Untersuchungen zu Lernprozessen und der Steuerung \u201enormalen\u201c Verhaltens entwickelt (z. B. pawlowscher Hund). Es geht dabei um die Behandlung problematischer bzw. unerw\u00fcnschter Verhaltensweisen sowie um das Erkennen der Bedingungen und Reize, die dieses Verhalten hervorrufen bzw. aufrechterhalten. Die kognitive Therapie befasst\u2026","rel":"","context":"In &quot;hpp&quot;","block_context":{"text":"hpp","link":"https:\/\/hppsycho.de\/mediathek\/category\/hpp\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16895,"url":"https:\/\/hppsycho.de\/mediathek\/2024\/12\/11\/techniken-der-verhaltenstherapie\/","url_meta":{"origin":16897,"position":1},"title":"Techniken der Verhaltenstherapie","author":"","date":false,"format":false,"excerpt":"Verhaltenstherapie besteht aus Techniken \u2026 bei denen man erw\u00fcnschtes Verhalten oder Denken erlernt Hierzu geh\u00f6ren soziales Kompetenztraining, Selbstsicherheitstraining, Lernen am Modell und Token-Programm. die ein unerw\u00fcnschtes Verhalten aufheben Dazu geh\u00f6ren die L\u00f6schung (Extinktion = Ersetzen), systematische Desensibilisierung und Flooding. und kognitiven Techniken, die immer ein Teil der Verhaltenstherapie sind. Kurzum,\u2026","rel":"","context":"In &quot;Verhaltenstherapie&quot;","block_context":{"text":"Verhaltenstherapie","link":"https:\/\/hppsycho.de\/mediathek\/category\/verhaltenstherapie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":16889,"url":"https:\/\/hppsycho.de\/mediathek\/2024\/12\/10\/verhaltenstherapie-2\/","url_meta":{"origin":16897,"position":2},"title":"Verhaltenstherapie","author":"","date":false,"format":false,"excerpt":"Die Verhaltenstherapie ist eine gut erforschte und sich st\u00e4ndig erweiternde Therapiemethode. Ihr Ziel sind die Behandlung definitiver Symptome, die vom Patienten ge\u00e4u\u00dfert werden,\u00a0unter Anwendung von lerntheoretischen bzw. kognitionspsychologischen Modellen,\u00a0sodass ein beschwerde- und symptomfreies Leben wieder m\u00f6glich ist. Die Symptome \u00e4u\u00dfern sich vor allem in der Reaktion oder den Auswirkungen auf\u2026","rel":"","context":"In &quot;Verhaltenstherapie&quot;","block_context":{"text":"Verhaltenstherapie","link":"https:\/\/hppsycho.de\/mediathek\/category\/verhaltenstherapie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":16901,"url":"https:\/\/hppsycho.de\/mediathek\/2024\/12\/11\/sork-schema\/","url_meta":{"origin":16897,"position":3},"title":"Sork-Schema","author":"","date":false,"format":false,"excerpt":"Das SORK-Modell wird in der Verhaltenstherapie als Struktur eingesetzt. Im Einzelnen bedeuten die Buchstaben: S (Stimulus)\u00a0bezeichnet eine \u00e4u\u00dfere oder innere Reizsituation. Der Stimulus erfasst die das Verhalten ausl\u00f6senden Bedingungen (In welcher Situation tritt das Verhalten auf?). Ich stehe im Kaufhaus und bekomme Herzschmerzen.\u00a0 O (Organismusvariable)\u00a0bezeichnet die individuellen biologischen und lerngeschichtlichen\u2026","rel":"","context":"In &quot;Verhaltenstherapie&quot;","block_context":{"text":"Verhaltenstherapie","link":"https:\/\/hppsycho.de\/mediathek\/category\/verhaltenstherapie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":16899,"url":"https:\/\/hppsycho.de\/mediathek\/2024\/12\/11\/indikationen-der-verhaltenstherapie\/","url_meta":{"origin":16897,"position":4},"title":"Indikationen der Verhaltenstherapie","author":"","date":false,"format":false,"excerpt":"Die Verhaltenstherapie wird bei nahezu alles St\u00f6rungen angewandt. Dazu geh\u00f6ren Krankheitsbilder, aber auch Interventionen in klinischen Alltag. So wird beispielsweise zur Verst\u00e4rkung positiven Verhaltens in Kliniken ein \"Token-Programm\" eingesetzt. Hier bekommen die Patienten bei entsprechendem Verhalten ein Token (eine erfundene W\u00e4hrung), den oder die sie dann zum Kauf von Dingen\u2026","rel":"","context":"In &quot;Verhaltenstherapie&quot;","block_context":{"text":"Verhaltenstherapie","link":"https:\/\/hppsycho.de\/mediathek\/category\/verhaltenstherapie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2019\/01\/psych_Fotolia_101789221_S.jpg?fit=693%2C693&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":5445,"url":"https:\/\/hppsycho.de\/mediathek\/2016\/10\/14\/11-lektion-psychotherapeutische-verfahren\/","url_meta":{"origin":16897,"position":5},"title":"11. Lektion &#8211; Psychotherapeutische Verfahren","author":"","date":false,"format":false,"excerpt":"Vor allem drei Therapieverfahren stehen hier im Vordergrund und Du solltest sie und die dahinterstehende Theorie gut kennen. Zur Theorie der Verhaltenstherapie geh\u00f6ren die klassische Konditionierung (der \"pawlowsche Hund\" - zwei Reize werden miteinander verbunden) die operante Konditionierung (Verhaltens\u00e4nderung durch Belohnung und Bestrafung) das Lernen am Modell (Nachahmung) Zur Anwendung\u2026","rel":"","context":"In &quot;learnletter&quot;","block_context":{"text":"learnletter","link":"https:\/\/hppsycho.de\/mediathek\/category\/learnletter\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2024\/03\/25_verhalten_pawlow.PNG?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2024\/03\/25_verhalten_pawlow.PNG?resize=350%2C200 1x, https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2024\/03\/25_verhalten_pawlow.PNG?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/hppsycho.de\/mediathek\/wp-content\/uploads\/2024\/03\/25_verhalten_pawlow.PNG?resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts\/16897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/comments?post=16897"}],"version-history":[{"count":0,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts\/16897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/media\/905"}],"wp:attachment":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/media?parent=16897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/categories?post=16897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/tags?post=16897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}