{"id":100,"count":123,"description":"","link":"https:\/\/hppsycho.de\/mediathek\/category\/hpp\/","name":"hpp","slug":"hpp","taxonomy":"category","parent":0,"meta":[],"z_taxonomy_image_url":"https:\/\/hppsycho.de\/mediathek\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","_links":{"self":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/categories\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hppsycho.de\/mediathek\/wp-json\/wp\/v2\/posts?categories=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}